{"id":1157,"date":"2023-07-11T16:35:40","date_gmt":"2023-07-11T14:35:40","guid":{"rendered":"https:\/\/orthodiag.com\/home\/"},"modified":"2024-07-05T11:33:03","modified_gmt":"2024-07-05T09:33:03","slug":"home","status":"publish","type":"page","link":"https:\/\/orthodiag.com\/de\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1157\" class=\"elementor elementor-1157 elementor-236\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15bebc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"15bebc6\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fba1fb\" data-id=\"4fba1fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b212a77 wpr-dual-heading-icon-top elementor-invisible elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"b212a77\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h1 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"first\">Eine kieferorthop\u00e4dische Selbstdiagnose<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"second\">von Ihrem Telefon aus<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/h1>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >Ortho-diag ist die Anwendung, mit der Sie eine kieferorthop\u00e4dische Selbstdiagnose erstellen, sich ein Bild von der Behandlung machen und einen Termin vereinbaren k\u00f6nnen!<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d2617f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"d2617f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-48d162a elementor-invisible\" data-id=\"48d162a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e143115 elementor-widget elementor-widget-image\" data-id=\"e143115\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.nohvinvestment.orthodiag&#038;pli=1\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"854\" height=\"245\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/Google-Play.png\" class=\"attachment-full size-full wp-image-103\" alt=\"\" srcset=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/Google-Play.png 854w, https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/Google-Play-300x86.png 300w, https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/Google-Play-768x220.png 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af3fddf elementor-invisible\" data-id=\"af3fddf\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c9e9c6 elementor-widget elementor-widget-image\" data-id=\"7c9e9c6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/apps.apple.com\/fr\/app\/orthodiag\/id6473542174?l=en-GB\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"854\" height=\"245\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/App-Store.png\" class=\"attachment-full size-full wp-image-102\" alt=\"\" srcset=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/App-Store.png 854w, https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/App-Store-300x86.png 300w, https:\/\/orthodiag.com\/wp-content\/uploads\/2023\/07\/App-Store-768x220.png 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab78ade elementor-invisible elementor-widget elementor-widget-image\" data-id=\"ab78ade\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1153\" height=\"1200\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-1.png\" class=\"attachment-full size-full wp-image-424\" alt=\"\" srcset=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-1.png 1153w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-1-288x300.png 288w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-1-984x1024.png 984w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-1-768x799.png 768w\" sizes=\"(max-width: 1153px) 100vw, 1153px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c824764 elementor-widget elementor-widget-spacer\" data-id=\"c824764\" data-element_type=\"widget\" id=\"orthodiag\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-614a182 elementor-reverse-laptop elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"614a182\" data-element_type=\"section\" id=\"autodiag\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42a2461 elementor-invisible\" data-id=\"42a2461\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84c673b elementor-widget elementor-widget-video\" data-id=\"84c673b\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/05\/video-orthodiag-mode-d-emploi.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-834692a elementor-invisible\" data-id=\"834692a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40f6f98 elementor-widget elementor-widget-heading\" data-id=\"40f6f98\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Machen Sie eine Selbstdiagnose<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c317fb elementor-widget elementor-widget-text-editor\" data-id=\"9c317fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Mit einem Klick erhalten Sie:<\/p>\n<ul>\n<li>Eine Selbstdiagnose<\/li>\n<li>Eine Behandlungsempfehlung<\/li>\n<li>Eine Preisspanne<\/li>\n<li>Eine Bearbeitungszeit<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1244728 elementor-widget elementor-widget-spacer\" data-id=\"1244728\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-633b121 elementor-widget elementor-widget-text-editor\" data-id=\"633b121\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Mit einem Klick k\u00f6nnen Sie au\u00dferdem:<\/p>\n<ul>\n<li>Greifen Sie auf eine Online-Beratung zu<\/li>\n<li>Vereinbaren Sie einen Termin mit dem Behandler<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b919c elementor-widget elementor-widget-spacer\" data-id=\"70b919c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d7a31 wpr-button-icon-style-inline wpr-button-icon-position-right elementor-widget elementor-widget-wpr-button\" data-id=\"48d7a31\" data-element_type=\"widget\" data-widget_type=\"wpr-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\n\t\t\t\n\t\t\n\t\t<div class=\"wpr-button-wrap elementor-clearfix\">\n\t\t<a class=\"wpr-button wpr-button-effect wpr-button-none\" data-text=\"Gehen\" href=\"#contact\">\n\t\t\t\n\t\t\t<span class=\"wpr-button-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"wpr-button-text\">Erfahren Sie mehr<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\n\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6745aea elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6745aea\" data-element_type=\"section\" id=\"solutions\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21eb9eb\" data-id=\"21eb9eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb3dd2d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fb3dd2d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bezahlung eines Pakets <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-896a505 elementor-widget elementor-widget-text-editor\" data-id=\"896a505\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Orthodiag erm\u00f6glicht Ihnen den Zugriff auf Ihre Diagnose im synthetischen Bild sowie auf eine von <strong>Dr. Isabelle Grier<\/strong> empfohlene Behandlung.<\/p>\n<p>Sie k\u00f6nnen auf <strong>Orthodiag<\/strong> zugreifen w\u00e4hrend:<\/p>\n<ul>\n<li>30 Minuten f\u00fcr 6 CHF<\/li>\n<li>6 Stunden f\u00fcr 12 CHF<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7a239f elementor-widget elementor-widget-spacer\" data-id=\"b7a239f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9adc605 elementor-widget elementor-widget-text-editor\" data-id=\"9adc605\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Mit diesem Zugriff k\u00f6nnen Sie Folgendes vermeiden:<\/p>\n<ul>\n<li>Ein Ausflug zum Kieferorthop\u00e4den<\/li>\n<li>Die Kosten einer teuren Erstberatung<\/li>\n<li>Verpassen der M\u00f6glichkeit einer medizinischen und \u00e4sthetischen Behandlung<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1025e49\" data-id=\"1025e49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06e7e31 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"06e7e31\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3337\" height=\"3337\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2.png\" class=\"attachment-full size-full wp-image-459\" alt=\"\" srcset=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2.png 3337w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2-300x300.png 300w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2-1024x1024.png 1024w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2-150x150.png 150w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2-768x768.png 768w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2-1536x1536.png 1536w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Design-sans-titre-2-2048x2048.png 2048w\" sizes=\"(max-width: 3337px) 100vw, 3337px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6a46e41 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"6a46e41\" data-element_type=\"container\" id=\"propos\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-37b188b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"37b188b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4225964 elementor-widget elementor-widget-image\" data-id=\"4225964\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"857\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Screenshot-2024-01-17-at-11.02.12-1024x914.png\" class=\"attachment-large size-large wp-image-357\" alt=\"\" srcset=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Screenshot-2024-01-17-at-11.02.12-1024x914.png 1024w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Screenshot-2024-01-17-at-11.02.12-300x268.png 300w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Screenshot-2024-01-17-at-11.02.12-768x686.png 768w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Screenshot-2024-01-17-at-11.02.12-1536x1372.png 1536w, https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/Screenshot-2024-01-17-at-11.02.12.png 1944w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6385868 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"6385868\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3634b96 elementor-widget elementor-widget-heading\" data-id=\"3634b96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihr Spezialist f\u00fcr Kieferorthop\u00e4die<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f57955 elementor-widget elementor-widget-text-editor\" data-id=\"1f57955\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Die <strong>Orthodiag<\/strong>-Anwendung wurde von <strong>Dr. Isabelle Grier <\/strong> (CESMO, Mention Orthodontie Paris VII) entworfen. <\/p>\n<p><strong>Doktor Grier <\/strong> arbeitet seit 30 Jahren mit Kindern, Jugendlichen und Erwachsenen in der unsichtbaren Kieferorthop\u00e4die bzw. Lingualkieferorthop\u00e4die. <\/p>\n<p>Mittlerweile hat es seinen Sitz in der Schweiz in Neuch\u00e2tel und Lausanne.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0323d19 elementor-widget elementor-widget-button\" data-id=\"0323d19\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/orthodontiste-dentiste.ch\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Entdecken Sie die B\u00fcros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-759204b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"759204b\" data-element_type=\"section\" id=\"rdv\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-221fc27\" data-id=\"221fc27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a16308 elementor-widget elementor-widget-heading\" data-id=\"5a16308\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nehmen <br>Termin<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb24c61 elementor-widget elementor-widget-text-editor\" data-id=\"bb24c61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sie k\u00f6nnen einen Termin in einem der beiden B\u00fcros von Doktor Isabelle Grier in der Schweiz (Neuch\u00e2tel oder Lausanne) vereinbaren.<\/p>\n<p>Oder Sie wenden sich an die n\u00e4chstgelegene kieferorthop\u00e4dische Praxis, wenn Sie nicht in der Schweiz oder in den Kantonen Waadt und Neuenburg ans\u00e4ssig sind.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67c17e9 elementor-invisible\" data-id=\"67c17e9\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInDown&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544d1bb elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"544d1bb\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/traitement-debut.png\" alt=\"traitement-debut\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/diagnostic-age.png\" alt=\"diagnostic-age\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/diagnostic-dentition.png\" alt=\"diagnostic-dentition\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/resultat-diagnostic.png\" alt=\"resultat-diagnostic\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/traitement.png\" alt=\"traitement\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/01\/rendez-vous.png\" alt=\"rendez-vous\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3637badf e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"3637badf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c5984f elementor-widget elementor-widget-heading\" data-id=\"1c5984f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cdf5e9e elementor-widget elementor-widget-accordion\" data-id=\"4cdf5e9e\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>.elementor-accordion{text-align:start}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1281\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1281\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wozu dient die OrthoDiag-Anwendung, wenn Sie direkt einen Termin mit Doktor Grier vereinbaren k\u00f6nnen? <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1281\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1281\"><p><span style=\"font-weight: 400;\">Um kieferorthop\u00e4dischen Problemen vorzubeugen und bei Bedarf schnell eingreifen zu k\u00f6nnen, ist eine regelm\u00e4\u00dfige \u00dcberwachung der eigenen Zahngesundheit unerl\u00e4sslich. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wenn das Problem behoben ist und das Problem auftritt, wird es schwierig, das Problem zu beheben. Durch die Konsultation des Antrags k\u00f6nnen Sie sich einen \u00dcberblick \u00fcber das zu planende Budget, die Behandlungszeit und anschlie\u00dfend eine erste medizinische Meinung verschaffen und anschlie\u00dfend einen Termin f\u00fcr die \u00e4rztliche Best\u00e4tigung vereinbaren und m\u00f6glicherweise mit der Behandlung bei Doktor Grier beginnen.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1282\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1282\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Welche L\u00f6sungen bietet Doktor Grier an?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1282\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1282\"><p><span style=\"font-weight: 400;\">Die Praxen von Dr. Grier bieten haupts\u00e4chlich unsichtbare Behandlungen an, darunter:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Feste Ger\u00e4te:<\/b><span style=\"font-weight: 400;\">Linguale Mehrringspange<\/span><span style=\"font-weight: 400;\">Unterkiefer-\/Oberkiefer- oder sogar Unterkiefer-\/Oberkiefer-Buccal-Multibrackets, die es erm\u00f6glichen, pr\u00e4zise Kr\u00e4fte auszu\u00fcben, um die Z\u00e4hne schrittweise in die gew\u00fcnschte Position zu bewegen.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Wechselmedien:<\/b><span style=\"font-weight: 400;\">Transparente Unterkiefer-\/Oberkiefer-Aligner, die eine diskrete und komfortable L\u00f6sung zur Korrektur leichter bis mittelschwerer Zahnanomalien bieten.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Innovative Behandlungen:<\/b><span style=\"font-weight: 400;\">Die WIN-Lingualapparatur besteht aus einer festsitzenden Apparatur, die auf der Innenseite der Z\u00e4hne platziert wird und die Behandlung nahezu unsichtbar macht.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Es ist wichtig, Doktor Isabelle Grier zu konsultieren, um die f\u00fcr Ihre Situation am besten geeignete Behandlung zu bestimmen.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1283\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1283\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie lange dauert eine Behandlung?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1283\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1283\"><p><span style=\"font-weight: 400;\">Bei leichten F\u00e4llen betr\u00e4gt die Mindestdauer einer kieferorthop\u00e4dischen Behandlung etwa 3 bis 6 Monate. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bei sehr komplexen F\u00e4llen m\u00fcssen Sie mehr Zeit einplanen: Die Zahnspange muss maximal 36 Monate getragen werden.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1284\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1284\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie lange dauert eine Selbstdiagnose?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1284\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1284\"><p><span style=\"font-weight: 400;\">Die OrthoDiad-App : <\/span> <span style=\"font-weight: 400;\">Erm\u00f6glicht Ihnen den Zugriff auf Ihre Diagnose im synthetischen Bild sowie auf eine Bearbeitungszeit. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Preis<\/span> <span style=\"font-weight: 400;\">einer Eigendiagnose richtet sich nach der Nutzungsdauer der Anwendung:<\/span> <\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">30 Minuten f\u00fcr 6 CHF<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">6 Stunden f\u00fcr 12 CHF<\/span><\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1285\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1285\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie verbinde ich mich mit OrthoDiag?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1285\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1285\"><ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Laden Sie die App herunter. Laden Sie die App herunter (iOS, Android), \u00f6ffnen Sie sie,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Identifizieren Sie sich, <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Das ist es !<\/span><\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1286\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1286\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie bezahle ich bei OrthoDiag?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1286\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1286\"><p><span style=\"font-weight: 400;\">Mit der OrthoDiag-Anwendung k\u00f6nnen Sie einfach und schnell \u00fcber unsere sichere Plattform bezahlen. <\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90ff36e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"90ff36e\" data-element_type=\"container\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4ca37c2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"4ca37c2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-404b0b4 elementor-widget elementor-widget-heading\" data-id=\"404b0b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontaktiere uns<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93ecb6b elementor-widget elementor-widget-text-editor\" data-id=\"93ecb6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"caret-color: rgb(84, 89, 95); color: rgb(84, 89, 95);\">Wenn Sie Fragen oder W\u00fcnsche haben, hinterlassen Sie uns bitte eine Nachricht mit Ihren Kontaktdaten. Unsere Teams werden ihr Bestes tun, um diese zu beantworten.&nbsp;<\/p>\n<p style=\"caret-color: rgb(84, 89, 95); color: rgb(84, 89, 95);\">Abh\u00e4ngig von Ihrem Standort k\u00f6nnen Sie uns f\u00fcr weitere W\u00fcnsche auch telefonisch kontaktieren.&nbsp;<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd8ffcc elementor-widget elementor-widget-wpforms\" data-id=\"bd8ffcc\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style id=\"wpforms-css-vars-root\">\n\t\t\t\t:root {\n\t\t\t\t\t--wpforms-field-border-radius: 3px;\n--wpforms-field-border-style: solid;\n--wpforms-field-border-size: 1px;\n--wpforms-field-background-color: #ffffff;\n--wpforms-field-border-color: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-border-color-spare: rgba( 0, 0, 0, 0.25 );\n--wpforms-field-text-color: rgba( 0, 0, 0, 0.7 );\n--wpforms-field-menu-color: #ffffff;\n--wpforms-label-color: rgba( 0, 0, 0, 0.85 );\n--wpforms-label-sublabel-color: rgba( 0, 0, 0, 0.55 );\n--wpforms-label-error-color: #d63637;\n--wpforms-button-border-radius: 3px;\n--wpforms-button-border-style: none;\n--wpforms-button-border-size: 1px;\n--wpforms-button-background-color: #066aab;\n--wpforms-button-border-color: #066aab;\n--wpforms-button-text-color: #ffffff;\n--wpforms-page-break-color: #066aab;\n--wpforms-background-image: none;\n--wpforms-background-position: center center;\n--wpforms-background-repeat: no-repeat;\n--wpforms-background-size: cover;\n--wpforms-background-width: 100px;\n--wpforms-background-height: 100px;\n--wpforms-background-color: rgba( 0, 0, 0, 0 );\n--wpforms-background-url: none;\n--wpforms-container-padding: 0px;\n--wpforms-container-border-style: none;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-color: #000000;\n--wpforms-container-border-radius: 3px;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\n\t\t\t\t}\n\t\t\t<\/style><style id=\"wpforms-css-vars-elementor-widget-bd8ffcc\">\n\t\t\t\t.elementor-widget-wpforms.elementor-element-bd8ffcc {\n\t\t\t\t\t--wpforms-button-background-color: #DEC8CF;\n--wpforms-field-text-color: #666666;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\n\t\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-298\"><form id=\"wpforms-form-298\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"298\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/pages\/1157\" data-token=\"c1c50d37813eed10388de95000d0bf22\" data-token-time=\"1784154172\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-298-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-298-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Pr\u00e9nom\" aria-errormessage=\"wpforms-298-field_0-error\" required><label for=\"wpforms-298-field_0\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-298-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Nom\" aria-errormessage=\"wpforms-298-field_0-last-error\" required><label for=\"wpforms-298-field_0-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Nachname<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-298-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-298-field_3\" aria-hidden=\"false\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-298-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"T\u00e9l\u00e9phone\" aria-errormessage=\"wpforms-298-field_3-error\" required><\/div><div id=\"wpforms-298-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-298-field_1\" aria-hidden=\"false\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-298-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Email\" spellcheck=\"false\" aria-errormessage=\"wpforms-298-field_1-error\" required><\/div><div id=\"wpforms-298-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-298-field_2\" aria-hidden=\"false\">Message<\/label><textarea id=\"wpforms-298-field_2\" class=\"wpforms-field-large\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-298-field_2-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"298\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/pages\/1157\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-298\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/orthodiag.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Eine kieferorthop\u00e4dische Selbstdiagnose von Ihrem Telefon aus Ortho-diag ist die Anwendung, mit der Sie eine kieferorthop\u00e4dische Selbstdiagnose erstellen, sich ein Bild von der Behandlung machen und einen Termin vereinbaren k\u00f6nnen! https:\/\/orthodiag.com\/wp-content\/uploads\/2024\/05\/video-orthodiag-mode-d-emploi.mp4 Machen Sie eine Selbstdiagnose Mit einem Klick erhalten Sie: Eine Selbstdiagnose Eine Behandlungsempfehlung Eine Preisspanne Eine Bearbeitungszeit Mit einem Klick k\u00f6nnen Sie au\u00dferdem: Greifen Sie auf eine Online-Beratung zu Vereinbaren Sie einen Termin mit dem Behandler Erfahren Sie mehr Bezahlung eines Pakets Orthodiag erm\u00f6glicht Ihnen den Zugriff auf Ihre Diagnose im synthetischen Bild sowie auf eine von Dr. Isabelle Grier empfohlene Behandlung. Sie k\u00f6nnen auf Orthodiag zugreifen w\u00e4hrend: 30 Minuten f\u00fcr 6 CHF 6 Stunden f\u00fcr 12 CHF Mit diesem Zugriff k\u00f6nnen Sie Folgendes vermeiden: Ein Ausflug zum Kieferorthop\u00e4den Die Kosten einer teuren Erstberatung Verpassen der M\u00f6glichkeit einer medizinischen und \u00e4sthetischen Behandlung Ihr Spezialist f\u00fcr Kieferorthop\u00e4die Die Orthodiag-Anwendung wurde von Dr. Isabelle Grier (CESMO, Mention Orthodontie Paris VII) entworfen. Doktor Grier arbeitet seit 30 Jahren mit Kindern, Jugendlichen und Erwachsenen in der unsichtbaren Kieferorthop\u00e4die bzw. Lingualkieferorthop\u00e4die. Mittlerweile hat es seinen Sitz in der Schweiz in Neuch\u00e2tel und Lausanne. Entdecken Sie die B\u00fcros Nehmen Termin Sie k\u00f6nnen einen Termin in einem der beiden B\u00fcros von Doktor Isabelle Grier in der Schweiz (Neuch\u00e2tel oder Lausanne) vereinbaren. Oder Sie wenden sich an die n\u00e4chstgelegene kieferorthop\u00e4dische Praxis, wenn Sie nicht in der Schweiz oder in den Kantonen Waadt und Neuenburg ans\u00e4ssig sind. FAQs Wozu dient die OrthoDiag-Anwendung, wenn Sie direkt einen Termin mit Doktor Grier vereinbaren k\u00f6nnen? Um kieferorthop\u00e4dischen Problemen vorzubeugen und bei Bedarf schnell eingreifen zu k\u00f6nnen, ist eine regelm\u00e4\u00dfige \u00dcberwachung der eigenen Zahngesundheit unerl\u00e4sslich. Wenn das Problem behoben ist und das Problem auftritt, wird es schwierig, das Problem zu beheben. Durch die Konsultation des Antrags k\u00f6nnen Sie sich einen \u00dcberblick \u00fcber das zu planende Budget, die Behandlungszeit und anschlie\u00dfend eine erste medizinische Meinung verschaffen und anschlie\u00dfend einen Termin f\u00fcr die \u00e4rztliche Best\u00e4tigung vereinbaren und m\u00f6glicherweise mit der Behandlung bei Doktor Grier beginnen. Welche L\u00f6sungen bietet Doktor Grier an? Die Praxen von Dr. Grier bieten haupts\u00e4chlich unsichtbare Behandlungen an, darunter: Feste Ger\u00e4te:Linguale MehrringspangeUnterkiefer-\/Oberkiefer- oder sogar Unterkiefer-\/Oberkiefer-Buccal-Multibrackets, die es erm\u00f6glichen, pr\u00e4zise Kr\u00e4fte auszu\u00fcben, um die Z\u00e4hne schrittweise in die gew\u00fcnschte Position zu bewegen. Wechselmedien:Transparente Unterkiefer-\/Oberkiefer-Aligner, die eine diskrete und komfortable L\u00f6sung zur Korrektur leichter bis mittelschwerer Zahnanomalien bieten. Innovative Behandlungen:Die WIN-Lingualapparatur besteht aus einer festsitzenden Apparatur, die auf der Innenseite der Z\u00e4hne platziert wird und die Behandlung nahezu unsichtbar macht. Es ist wichtig, Doktor Isabelle Grier zu konsultieren, um die f\u00fcr Ihre Situation am besten geeignete Behandlung zu bestimmen. Wie lange dauert eine Behandlung? Bei leichten F\u00e4llen betr\u00e4gt die Mindestdauer einer kieferorthop\u00e4dischen Behandlung etwa 3 bis 6 Monate. Bei sehr komplexen F\u00e4llen m\u00fcssen Sie mehr Zeit einplanen: Die Zahnspange muss maximal 36 Monate getragen werden. Wie lange dauert eine Selbstdiagnose? Die OrthoDiad-App : Erm\u00f6glicht Ihnen den Zugriff auf Ihre Diagnose im synthetischen Bild sowie auf eine Bearbeitungszeit. Der Preis einer Eigendiagnose richtet sich nach der Nutzungsdauer der Anwendung: 30 Minuten f\u00fcr 6 CHF 6 Stunden f\u00fcr 12 CHF Wie verbinde ich mich mit OrthoDiag? Laden Sie die App herunter. Laden Sie die App herunter (iOS, Android), \u00f6ffnen Sie sie, Identifizieren Sie sich, Das ist es ! Wie bezahle ich bei OrthoDiag? Mit der OrthoDiag-Anwendung k\u00f6nnen Sie einfach und schnell \u00fcber unsere sichere Plattform bezahlen. Kontaktiere uns Wenn Sie Fragen oder W\u00fcnsche haben, hinterlassen Sie uns bitte eine Nachricht mit Ihren Kontaktdaten. Unsere Teams werden ihr Bestes tun, um diese zu beantworten.&nbsp; Abh\u00e4ngig von Ihrem Standort k\u00f6nnen Sie uns f\u00fcr weitere W\u00fcnsche auch telefonisch kontaktieren.&nbsp; Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire. Nom * Pr\u00e9nomNom T\u00e9l\u00e9phone *E-mail *Message Envoyer<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Orthodiag \u2013 Anwendung zur Selbstdiagnose der Kieferorthop\u00e4die","_seopress_titles_desc":"Orthodiag ist die Anwendung, mit der Sie eine kieferorthop\u00e4dische Selbstdiagnose erstellen, sich ein Bild von der Behandlung machen und einen Termin vereinbaren k\u00f6nnen!","_seopress_robots_index":"","footnotes":""},"class_list":["post-1157","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/pages\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":0,"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/pages\/1157\/revisions"}],"wp:attachment":[{"href":"https:\/\/orthodiag.com\/de\/wp-json\/wp\/v2\/media?parent=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}